{"id":1633,"date":"2012-07-31T21:03:35","date_gmt":"2012-07-31T21:03:35","guid":{"rendered":"https:\/\/adrianacisneros.com\/?p=1633"},"modified":"2014-05-05T05:57:17","modified_gmt":"2014-05-05T05:57:17","slug":"the-cisneros-group-of-companies-launched-cuponidad-in-venezuela","status":"publish","type":"post","link":"https:\/\/www.adrianacisneros.com\/es\/the-cisneros-group-of-companies-launched-cuponidad-in-venezuela\/","title":{"rendered":"Nuestra m\u00c3\u00a1s reciente iniciativa \u00e2\u20ac\u201c Cuponidad. Reformulando el negocio de cupones en Latinoam\u00c3\u00a9rica con el socio ideal"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: left;\">Me complace mucho anunciar nuestra m\u00c3\u00a1s reciente iniciativa: nos hemos asociado a Cuponidad para su lanzamiento en Venezuela. A partir de este momento, Cuponidad ofrecer\u00c3\u00a1 a los consumidores venezolanos un sitio para adquirir servicios, productos y paquetes de viaje con grandes descuentos. Este ser\u00c3\u00a1 s\u00c3\u00b3lo el primero de muchos lanzamientos que esperamos hacer en Am\u00c3\u00a9rica Latina.<\/p>\n<p style=\"text-align: center;\"><iframe src=\"https:\/\/www.youtube.com\/embed\/LMeCW3o9vOs\" height=\"315\" width=\"420\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n<p>Cuponidad, muy similar al concepto basado en Estados Unidos, Groupon, Inc., tiene todo para ser exitoso. Groupon ha presentado niveles de utilidad crecientes desde su lanzamiento, con ingresos que ascendieron un 89 por ciento en Q1 del 2012 alcanzando $559,3 millones, en comparaci\u00c3\u00b3n con $295,5 millones obtenidos durante el 2011. De igual forma, los costos de mercadeo de la empresa estadounidense bajaron el a\u00c3\u00b1o pasado de 78 por ciento a 21 por ciento del total de ingresos, favoreciendo el aumento de las utilidades a un nuevo nivel.<\/p>\n<p><span class=\"pullquote\">El comercio electr\u00c3\u00b3nico en Am\u00c3\u00a9rica Latina, se encuentra en crecimiento, alcanzando una valoraci\u00c3\u00b3n de $70 mil millones de d\u00c3\u00b3lares al a\u00c3\u00b1o<\/span> y presentando un aumento de un 30 por ciento en el n\u00c3\u00bamero de visitas a negocios online durante el a\u00c3\u00b1o pasado. Considerando el continuo crecimiento de este mercado, Cuponidad tendr\u00c3\u00a1 con seguridad, un crecimiento similar o a\u00c3\u00ban mayor al de Groupon, Inc.<\/p>\n<p>De igual forma, la regi\u00c3\u00b3n ha experimentado uno de los m\u00c3\u00a1s grandes auges en la penetraci\u00c3\u00b3n de Internet, con m\u00c3\u00a1s del 86 por ciento de la poblaci\u00c3\u00b3n con acceso a Internet y con una de las m\u00c3\u00a1s altas tasas de penetraci\u00c3\u00b3n de tecnolog\u00c3\u00ada celular del mundo. Cuponidad tomar\u00c3\u00a1 ventaja del alcance digital en Am\u00c3\u00a9rica Latina, desarrollando ofertas a trav\u00c3\u00a9s de diferentes plataformas digitales.<\/p>\n<p>Durante mi m\u00c3\u00a1s reciente visita a Caracas, convers\u00c3\u00a9 con Daniel Burdeinick y Joel Cohen, los dos co-fundadores de Cuponidad. Nuestro equipo estuvo sumamente impresionado con su visi\u00c3\u00b3n de la empresa, lanzada por primera vez en Colombia en el 2010. Nos emociona colaborar con una empresa que se encuentra camino a convertirse en un l\u00c3\u00adder regional del comercio electr\u00c3\u00b3nico, creciendo exponencialmente tanto en cobertura como en ganancias.<\/p>\n<p>Conoce m\u00c3\u00a1s de esta nueva iniciativa\u00e2\u20ac\u00a6<\/p>\n<p><iframe id=\"doc_25552\" src=\"https:\/\/www.scribd.com\/embeds\/101677363\/content?start_page=1&#038;view_mode=list&#038;access_key=key-1mftegcapw3cw4yu6ezd\" height=\"600\" width=\"100%\" frameborder=\"0\" scrolling=\"no\" data-aspect-ratio=\"0.75\" data-auto-height=\"true\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Me complace mucho anunciar nuestra m\u00c3\u00a1s reciente iniciativa: nos hemos asociado a Cuponidad para su lanzamiento en Venezuela. A partir de este momento, Cuponidad ofrecer\u00c3\u00a1 a los consumidores venezolanos un sitio para adquirir servicios, productos y paquetes de viaje con grandes descuentos. Este ser\u00c3\u00a1 s\u00c3\u00b3lo el primero de muchos lanzamientos que esperamos hacer en Am\u00c3\u00a9rica Latina.<\/p>\n","protected":false},"author":1,"featured_media":2928,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/posts\/1633"}],"collection":[{"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":13,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"predecessor-version":[{"id":3622,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/posts\/1633\/revisions\/3622"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/media\/2928"}],"wp:attachment":[{"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adrianacisneros.com\/es\/wp-json\/wp\/v2\/tags?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}